{"id":668,"date":"2021-11-30T14:42:07","date_gmt":"2021-11-30T13:42:07","guid":{"rendered":"https:\/\/www.neoconsulting-projets2.fr\/?post_type=product&#038;p=668"},"modified":"2026-06-14T19:39:35","modified_gmt":"2026-06-14T17:39:35","slug":"bon-cadeau-decouverte","status":"publish","type":"product","link":"https:\/\/www.pays-basque-experience.com\/es\/produit\/bon-cadeau-decouverte\/","title":{"rendered":"Bon Cadeau D\u00e9couverte en 4&#215;4"},"content":{"rendered":"<p data-start=\"129\" data-end=\"545\">En r\u00e9servant une excursion en 4&#215;4 \u00e0 nos c\u00f4t\u00e9s, vous ne vivez pas qu\u2019une simple balade : c\u2019est un <strong data-start=\"277\" data-end=\"336\">v\u00e9ritable moment de partage, d\u2019\u00e9vasion et de d\u00e9couverte<\/strong> que vous offrez. Laissez-vous emporter <strong data-start=\"381\" data-end=\"398\">hors du temps<\/strong>, sur les chemins secrets du Pays Basque, entre montagnes et traditions.<br data-start=\"477\" data-end=\"480\" \/><strong>Une aventure unique, pleine de sensations et d\u2019authenticit\u00e9 !<\/strong><\/p>\n<p data-start=\"547\" data-end=\"933\">Nos excursions sont <strong data-start=\"567\" data-end=\"598\">accessibles \u00e0 tous les \u00e2ges<\/strong> et <strong data-start=\"602\" data-end=\"647\">encadr\u00e9es par nos instructeurs passionn\u00e9s<\/strong>. Vous pouvez <strong data-start=\"661\" data-end=\"682\">prendre le volant<\/strong> pour une exp\u00e9rience encore plus immersive, ou <strong data-start=\"729\" data-end=\"758\">vous d\u00e9tendre en passager<\/strong> et profiter du paysage.<br data-start=\"782\" data-end=\"785\" \/>Chaque sortie se d\u00e9roule <strong data-start=\"810\" data-end=\"829\">en petit groupe<\/strong>, dans une ambiance conviviale et chaleureuse, pour partager ensemble la beaut\u00e9 et l\u2019\u00e2me du Pays Basque.<\/p>\n<p>Nous vous proposons plusieurs formules bon cadeau\u00a0\u00e0 <strong>utiliser au printemps \/ \u00e9t\u00e9 2026 ou 2027. Le d\u00e9part se fait depuis Bidart.<\/strong><\/p>\n<ul>\n<li><strong>D\u00e9couverte 1\/2 journ\u00e9e :<\/strong> 179\u20ac pour 2 personnes ou 349\u20ac pour 4\/5 personnes*<\/li>\n<li><strong>Coucher de soleil avec ap\u00e9ritif : <\/strong>199\u20ac pour 2 personnes ou 349\u20ac pour 4\/5 personnes**<\/li>\n<li><strong>Journ\u00e9e VIP : <\/strong>690\u20ac pour 4\/5 personnes (hors restaurant)***<\/li>\n<\/ul>\n<p><strong>Pour les r\u00e9servations de 2 ou 3 personnes : <\/strong>Vous partagerez l\u2019aventure \u00e0 bord d\u2019un v\u00e9hicule avec d\u2019autres participants ainsi qu\u2019avec nos accompagnateurs.<br data-start=\"363\" data-end=\"366\" \/>Votre petit groupe reste \u00e9videmment ensemble pour profiter pleinement de l\u2019exp\u00e9rience dans une ambiance conviviale et chaleureuse.<br \/>\n<strong>Pour les r\u00e9servations de 4\/5 personnes (non VIP)<\/strong> : Vous profitez d\u2019un 4&#215;4 ou d&#8217;une 4L rien que pour vous !<br data-start=\"585\" data-end=\"588\" \/>Cependant, l\u2019exp\u00e9rience se vit en convoi, aux c\u00f4t\u00e9s d\u2019autres participants pr\u00e9sents sur la m\u00eame sortie.<br data-start=\"694\" data-end=\"697\" \/>Votre groupe reste autonome dans son propre v\u00e9hicule, tout en \u00e9tant guid\u00e9 par l\u2019un de nos instructeurs, qui se trouve dans un autre 4&#215;4 en t\u00eate du groupe.<br \/>\n<strong>Pour la r\u00e9servation d&#8217;une journ\u00e9e VIP :<\/strong> Une journ\u00e9e d\u2019exception totalement privatis\u00e9e : vous \u00eates seuls \u00e0 vivre l\u2019aventure, sans autres participants ext\u00e9rieurs.<br data-start=\"1045\" data-end=\"1048\" \/>Nous vous mettons \u00e0 disposition un 4&#215;4 pour la journ\u00e9e, accompagn\u00e9 uniquement par notre \u00e9quipe dans un autre 4&#215;4 qui vous guide, \u00e0 votre rythme et selon vos envies.<br \/>\nD\u00e9jeuner libre : s\u00e9lectionnez le restaurant ou l\u2019ambiance culinaire qui vous fait r\u00eaver : restaurant insolite en pleine nature, pique-nique en montagne, restaurant gastronomique\u2026 et nous adaptons l\u2019itin\u00e9raire selon votre choix.<\/p>\n<p data-start=\"0\" data-end=\"118\"><em>* Pour la formule D\u00e9couverte 1\/2 journ\u00e9e : capacit\u00e9 maximale de 4 personnes pour une 4L et 5 personnes pour un 4&#215;4.<\/em><br \/>\n<em><span style=\"font-size: 16px;\">** Attention : lorsque vous choisissez un v\u00e9hicule privatif, l\u2019ap\u00e9ritif n\u2019est pas inclus. Un suppl\u00e9ment de 15 \u20ac par personne sera \u00e0 pr\u00e9voir pour l\u2019ap\u00e9ritif d\u00eenatoire.<br \/>\n<\/span><span style=\"font-size: 16px;\">*** Journ\u00e9e VIP : pour le d\u00e9jeuner, c\u2019est vous qui choisissez l\u2019exp\u00e9rience qui vous ressemble : restaurant typique, pique-nique aux saveurs locales ou table gastronomique basque (d\u00e9jeuner non inclus dans le tarif).<\/span><\/em><\/p>\n<p><em><strong>D\u00e9tails sur les bons :<\/strong> Une fois le bon cadeau achet\u00e9 en ligne, une confirmation vous sera envoy\u00e9e et vous recevrez \u00e9galement le bon cadeau d\u00e9mat\u00e9rialis\u00e9 sous forme de PDF pr\u00eat \u00e0 imprimer. Ces bons sont valables jusqu&#8217;au 31 d\u00e9cembre 2027.\u00a0 Ces excursions se d\u00e9roulent en groupe, aux c\u00f4t\u00e9s d\u2019autres participants au printemps et en \u00e9t\u00e9. Les dates pr\u00e9cises de ces excursions sont mentionn\u00e9es<\/em><\/p>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Nous vous proposons plusieurs formules bon cadeau\u00a0\u00e0 <strong>utiliser au printemps \/ \u00e9t\u00e9 2026 ou 2027. Le d\u00e9part se fait depuis Bidart.<\/strong><\/p>\n<ul>\n<li><strong>D\u00e9couverte 1\/2 journ\u00e9e :<\/strong> 179\u20ac pour 2 personnes ou 349\u20ac pour 4\/5 personnes*<\/li>\n<li><strong>Coucher de soleil avec ap\u00e9ritif : <\/strong>199\u20ac pour 2 personnes ou 349\u20ac pour 4\/5 personnes**<\/li>\n<li><strong>Journ\u00e9e VIP : <\/strong>690\u20ac pour 4\/5 personnes (hors restaurant)***\n<p><strong>Au volant de nos v\u00e9hicules<\/strong>, prenez part pleinement \u00e0 l\u2019exp\u00e9rience et vivez l\u2019aventure de l\u2019int\u00e9rieur. Bien entendu, si vous pr\u00e9f\u00e9rez simplement profiter du paysage, vous pouvez \u00e9galement rester passager.<\/li>\n<\/ul>\n<p><strong>Au programme de la demi-journ\u00e9e :<\/strong> \u00e9chappez-vous pendant 3h et traversez des villages rouges et blancs surveill\u00e9s par La Rhune, en alternant routes, chemins et anciennes pistes des contrebandiers. Ce programme comporte des arr\u00eats pour admirer la vue. Une immersion rare, guid\u00e9e et comment\u00e9e par nos experts, qui vous m\u00e8ne dans des lieux et passages que vous ne pourriez certainement pas d\u00e9couvrir par vous-m\u00eame.<br \/>\n<em style=\"font-size: 16px;\">* Pour la formule D\u00e9couverte 1\/2 journ\u00e9e : capacit\u00e9 maximale de 4 personnes pour une 4L et 5 personnes pour un 4&#215;4.<\/em><\/p>\n<p data-start=\"0\" data-end=\"118\">\n<p><strong>Au programme de la soir\u00e9e Coucher de Soleil<\/strong> : D\u00e9part de cette excursion 4\u00d74 d&#8217;exception depuis notre base de Bidart \u00e0 19h00 vers les <strong>montagnes basques.<\/strong> Notre \u00e9quipe vous am\u00e8ne sur les pistes du Pays Basque, hors de sentiers battus. Un <strong>ap\u00e9ritif Sunset<\/strong>, vous sera servi en\u00a0<strong>pleine nature avec une vue magnifique sur la mer et les montagnes<\/strong>. Ce programme comporte des arr\u00eats pour admirer la vue puis un ap\u00e9ritif surplombant le Pays Basque. Comptez environ 3h15 d&#8217;exp\u00e9rience dont 1h d&#8217;ap\u00e9ritif. Une exp\u00e9rience unique, vous ouvrant des panoramas et des moments rares.<br \/>\n<em>**<strong>Attention<\/strong>, lorsque vous prenez un v\u00e9hicule privatif l\u2019ap\u00e9ritif n\u2019est pas inclus. Il faudra compter 15 euros suppl\u00e9mentaires par personne en suppl\u00e9ment pour cet ap\u00e9ritif dinatoire.<\/em><\/p>\n<p><strong>Au programme pour la journ\u00e9e VIP<\/strong> : Une exp\u00e9rience totalement privatis\u00e9e : <strong data-start=\"211\" data-end=\"253\">votre groupe est seul avec notre guide<\/strong>, pour d\u00e9couvrir l\u2019arri\u00e8re-pays comme personne. Gr\u00e2ce au 4&#215;4, vous empruntez <strong data-start=\"330\" data-end=\"386\">des pistes confidentielles et des routes peu connues<\/strong>, bien loin des sentiers classiques, pour acc\u00e9der aux panoramas et secrets les mieux gard\u00e9s du Pays Basque.<\/p>\n<p data-start=\"495\" data-end=\"700\">Au d\u00e9part de la c\u00f4te, vous traversez les villages embl\u00e9matiques (<strong data-start=\"561\" data-end=\"632\">Arcangues, Saint-P\u00e9e-sur-Nivelle, Espelette, Itxassou, Ainhoa, Sare&#8230;)<\/strong>\u00a0avec possibilit\u00e9 de poursuivre jusqu\u2019en Espagne selon vos envies.<\/p>\n<p><em>***D\u00e9jeuner non-compris : Le d\u00e9jeuner se fera en fonction de vos envies : pique-nique en pleine nature, &#8220;venta&#8221; traditionnelle, restaurant gastronomique&#8230; tout est possible.<br \/>\n<\/em><\/p>\n<p><strong>Exp\u00e9rience \u00e0 bord<\/strong> :<br \/>\n<strong>Pour les r\u00e9servations de 2 personnes : <\/strong>Vous partagerez l\u2019aventure \u00e0 bord de nos v\u00e9hicules avec nos accompagnateurs. Bien entendu, votre petit groupe restera ensemble, pour profiter pleinement de l\u2019exp\u00e9rience dans une ambiance conviviale et chaleureuse.<br \/>\n<strong>Pour les r\u00e9servations de 4\/5 personnes<\/strong> : Vous profiterez d\u2019un v\u00e9hicule privatis\u00e9 rien que pour vous ! Le groupe vivra l\u2019exp\u00e9rience en toute intimit\u00e9, guid\u00e9 par l\u2019un de nos instructeurs certifi\u00e9s (qui sera dans un autre v\u00e9hicule devant vous)<\/p>\n<p><strong>Niveau<\/strong> : Aucun niveau particulier n\u2019est requis. Nos guides, formateurs dipl\u00f4m\u00e9s, sont l\u00e0 pour vous accompagner \u00e0 chaque instant : vous guider, vous conseiller et vous rassurer si n\u00e9cessaire. Vous n\u2019avez qu\u2019\u00e0 vous laisser porter par l\u2019exp\u00e9rience. Seul un permis en cours de validit\u00e9 est demand\u00e9.<\/p>\n<p><b>Dates <\/b>:\u00a0 Plusieurs dates sont propos\u00e9es pour 2026 du mois d&#8217;avril au mois de novembre. Le choix se fait sur ces dates. L\u2019exp\u00e9rience VIP est programm\u00e9e selon vos pr\u00e9f\u00e9rences : vous choisissez la date, nous nous occupons du reste. Vous aurez l&#8217;embarras du choix pour choisir le cr\u00e9neau qui vous convient.<\/p>","protected":false},"featured_media":6459,"template":"","meta":{"site-sidebar-layout":"default","site-content-layout":"default","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"default","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}}},"product_brand":[],"product_cat":[21],"product_tag":[],"class_list":["post-668","product","type-product","status-publish","has-post-thumbnail","product_cat-pays-basque-experience","desktop-align-left","tablet-align-left","mobile-align-left","ast-product-gallery-layout-horizontal-slider","ast-product-single-variable","ast-product-tabs-layout-horizontal","first","instock","taxable","shipping-taxable","purchasable","product-type-variable","has-default-attributes"],"booking_location":null,"booking_location_type":null,"booking_duration":null,"booking_duration_unit":null,"booking_buffer":null,"booking_cost":null,"booking_resources":null,"exclude_global_add_ons":[],"addons":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.5 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Bon Cadeau D\u00e9couverte en 4x4 - Pays Basque Experience<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pays-basque-experience.com\/es\/producto-2\/bon-cadeau-decouverte\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bon Cadeau D\u00e9couverte en 4x4\" \/>\n<meta property=\"og:description\" content=\"Nous vous proposons plusieurs formules bon cadeau\u00a0\u00e0 utiliser au printemps \/ \u00e9t\u00e9 2026 ou 2027. Le d\u00e9part se fait depuis Bidart.   D\u00e9couverte 1\/2 journ\u00e9e : 179\u20ac pour 2 personnes ou 349\u20ac pour 4\/5 personnes*  Coucher de soleil avec ap\u00e9ritif : 199\u20ac pour 2 personnes ou 349\u20ac pour 4\/5 personnes**  Journ\u00e9e VIP : 690\u20ac pour 4\/5 personnes (hors restaurant)***  Au volant de nos v\u00e9hicules, prenez part pleinement \u00e0 l\u2019exp\u00e9rience et vivez l\u2019aventure de l\u2019int\u00e9rieur. Bien entendu, si vous pr\u00e9f\u00e9rez simplement profiter du paysage, vous pouvez \u00e9galement rester passager.  Au programme de la demi-journ\u00e9e : \u00e9chappez-vous pendant 3h et traversez des villages rouges et blancs surveill\u00e9s par La Rhune, en alternant routes, chemins et anciennes pistes des contrebandiers. Ce programme comporte des arr\u00eats pour admirer la vue. Une immersion rare, guid\u00e9e et comment\u00e9e par nos experts, qui vous m\u00e8ne dans des lieux et passages que vous ne pourriez certainement pas d\u00e9couvrir par vous-m\u00eame. * Pour la formule D\u00e9couverte 1\/2 journ\u00e9e : capacit\u00e9 maximale de 4 personnes pour une 4L et 5 personnes pour un 4x4.  Au programme de la soir\u00e9e Coucher de Soleil : D\u00e9part de cette excursion 4\u00d74 d&#039;exception depuis notre base de Bidart \u00e0 19h00 vers les montagnes basques. Notre \u00e9quipe vous am\u00e8ne sur les pistes du Pays Basque, hors de sentiers battus. Un ap\u00e9ritif Sunset, vous sera servi en\u00a0pleine nature avec une vue magnifique sur la mer et les montagnes. Ce programme comporte des arr\u00eats pour admirer la vue puis un ap\u00e9ritif surplombant le Pays Basque. Comptez environ 3h15 d&#039;exp\u00e9rience dont 1h d&#039;ap\u00e9ritif. Une exp\u00e9rience unique, vous ouvrant des panoramas et des moments rares. **Attention, lorsque vous prenez un v\u00e9hicule privatif l\u2019ap\u00e9ritif n\u2019est pas inclus. Il faudra compter 15 euros suppl\u00e9mentaires par personne en suppl\u00e9ment pour cet ap\u00e9ritif dinatoire.  Au programme pour la journ\u00e9e VIP : Une exp\u00e9rience totalement privatis\u00e9e : votre groupe est seul avec notre guide, pour d\u00e9couvrir l\u2019arri\u00e8re-pays comme personne. Gr\u00e2ce au 4x4, vous empruntez des pistes confidentielles et des routes peu connues, bien loin des sentiers classiques, pour acc\u00e9der aux panoramas et secrets les mieux gard\u00e9s du Pays Basque. Au d\u00e9part de la c\u00f4te, vous traversez les villages embl\u00e9matiques (Arcangues, Saint-P\u00e9e-sur-Nivelle, Espelette, Itxassou, Ainhoa, Sare...)\u00a0avec possibilit\u00e9 de poursuivre jusqu\u2019en Espagne selon vos envies. ***D\u00e9jeuner non-compris : Le d\u00e9jeuner se fera en fonction de vos envies : pique-nique en pleine nature, &quot;venta&quot; traditionnelle, restaurant gastronomique... tout est possible.   Exp\u00e9rience \u00e0 bord : Pour les r\u00e9servations de 2 personnes : Vous partagerez l\u2019aventure \u00e0 bord de nos v\u00e9hicules avec nos accompagnateurs. Bien entendu, votre petit groupe restera ensemble, pour profiter pleinement de l\u2019exp\u00e9rience dans une ambiance conviviale et chaleureuse. Pour les r\u00e9servations de 4\/5 personnes : Vous profiterez d\u2019un v\u00e9hicule privatis\u00e9 rien que pour vous ! Le groupe vivra l\u2019exp\u00e9rience en toute intimit\u00e9, guid\u00e9 par l\u2019un de nos instructeurs certifi\u00e9s (qui sera dans un autre v\u00e9hicule devant vous)  Niveau : Aucun niveau particulier n\u2019est requis. Nos guides, formateurs dipl\u00f4m\u00e9s, sont l\u00e0 pour vous accompagner \u00e0 chaque instant : vous guider, vous conseiller et vous rassurer si n\u00e9cessaire. Vous n\u2019avez qu\u2019\u00e0 vous laisser porter par l\u2019exp\u00e9rience. Seul un permis en cours de validit\u00e9 est demand\u00e9.  Dates :\u00a0 Plusieurs dates sont propos\u00e9es pour 2026 du mois d&#039;avril au mois de novembre. Le choix se fait sur ces dates. L\u2019exp\u00e9rience VIP est programm\u00e9e selon vos pr\u00e9f\u00e9rences : vous choisissez la date, nous nous occupons du reste. Vous aurez l&#039;embarras du choix pour choisir le cr\u00e9neau qui vous convient.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pays-basque-experience.com\/es\/producto-2\/bon-cadeau-decouverte\/\" \/>\n<meta property=\"og:site_name\" content=\"Pays Basque Experience\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-14T17:39:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.pays-basque-experience.com\/wp-content\/uploads\/2021\/11\/Coucher-soleil-groupe.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"787\" \/>\n\t<meta property=\"og:image:height\" content=\"525\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.pays-basque-experience.com\\\/produit\\\/bon-cadeau-decouverte\\\/\",\"url\":\"https:\\\/\\\/www.pays-basque-experience.com\\\/produit\\\/bon-cadeau-decouverte\\\/\",\"name\":\"Bon Cadeau D\u00e9couverte en 4x4 - Pays Basque Experience\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.pays-basque-experience.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.pays-basque-experience.com\\\/produit\\\/bon-cadeau-decouverte\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.pays-basque-experience.com\\\/produit\\\/bon-cadeau-decouverte\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.pays-basque-experience.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/Coucher-soleil-groupe.jpg\",\"datePublished\":\"2021-11-30T13:42:07+00:00\",\"dateModified\":\"2026-06-14T17:39:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.pays-basque-experience.com\\\/produit\\\/bon-cadeau-decouverte\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.pays-basque-experience.com\\\/produit\\\/bon-cadeau-decouverte\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.pays-basque-experience.com\\\/produit\\\/bon-cadeau-decouverte\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.pays-basque-experience.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/Coucher-soleil-groupe.jpg\",\"contentUrl\":\"https:\\\/\\\/www.pays-basque-experience.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/Coucher-soleil-groupe.jpg\",\"width\":787,\"height\":525},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.pays-basque-experience.com\\\/produit\\\/bon-cadeau-decouverte\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.pays-basque-experience.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Boutique\",\"item\":\"https:\\\/\\\/www.pays-basque-experience.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Bon Cadeau D\u00e9couverte en 4&#215;4\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.pays-basque-experience.com\\\/#website\",\"url\":\"https:\\\/\\\/www.pays-basque-experience.com\\\/\",\"name\":\"Pays Basque Experience\",\"description\":\"Aventures au Pays Basque - Rando 4x4 pays basque.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.pays-basque-experience.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.pays-basque-experience.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.pays-basque-experience.com\\\/#organization\",\"name\":\"Pays Basque Experience\",\"url\":\"https:\\\/\\\/www.pays-basque-experience.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.pays-basque-experience.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.pays-basque-experience.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/cropped-logo-21A1.png\",\"contentUrl\":\"https:\\\/\\\/www.pays-basque-experience.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/cropped-logo-21A1.png\",\"width\":300,\"height\":300,\"caption\":\"Pays Basque Experience\"},\"image\":{\"@id\":\"https:\\\/\\\/www.pays-basque-experience.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Bon Cadeau D\u00e9couverte en 4x4 - Pays Basque Experience","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pays-basque-experience.com\/es\/producto-2\/bon-cadeau-decouverte\/","og_locale":"es_ES","og_type":"article","og_title":"Bon Cadeau D\u00e9couverte en 4x4","og_description":"Nous vous proposons plusieurs formules bon cadeau\u00a0\u00e0 utiliser au printemps \/ \u00e9t\u00e9 2026 ou 2027. Le d\u00e9part se fait depuis Bidart.   D\u00e9couverte 1\/2 journ\u00e9e : 179\u20ac pour 2 personnes ou 349\u20ac pour 4\/5 personnes*  Coucher de soleil avec ap\u00e9ritif : 199\u20ac pour 2 personnes ou 349\u20ac pour 4\/5 personnes**  Journ\u00e9e VIP : 690\u20ac pour 4\/5 personnes (hors restaurant)***  Au volant de nos v\u00e9hicules, prenez part pleinement \u00e0 l\u2019exp\u00e9rience et vivez l\u2019aventure de l\u2019int\u00e9rieur. Bien entendu, si vous pr\u00e9f\u00e9rez simplement profiter du paysage, vous pouvez \u00e9galement rester passager.  Au programme de la demi-journ\u00e9e : \u00e9chappez-vous pendant 3h et traversez des villages rouges et blancs surveill\u00e9s par La Rhune, en alternant routes, chemins et anciennes pistes des contrebandiers. Ce programme comporte des arr\u00eats pour admirer la vue. Une immersion rare, guid\u00e9e et comment\u00e9e par nos experts, qui vous m\u00e8ne dans des lieux et passages que vous ne pourriez certainement pas d\u00e9couvrir par vous-m\u00eame. * Pour la formule D\u00e9couverte 1\/2 journ\u00e9e : capacit\u00e9 maximale de 4 personnes pour une 4L et 5 personnes pour un 4x4.  Au programme de la soir\u00e9e Coucher de Soleil : D\u00e9part de cette excursion 4\u00d74 d'exception depuis notre base de Bidart \u00e0 19h00 vers les montagnes basques. Notre \u00e9quipe vous am\u00e8ne sur les pistes du Pays Basque, hors de sentiers battus. Un ap\u00e9ritif Sunset, vous sera servi en\u00a0pleine nature avec une vue magnifique sur la mer et les montagnes. Ce programme comporte des arr\u00eats pour admirer la vue puis un ap\u00e9ritif surplombant le Pays Basque. Comptez environ 3h15 d'exp\u00e9rience dont 1h d'ap\u00e9ritif. Une exp\u00e9rience unique, vous ouvrant des panoramas et des moments rares. **Attention, lorsque vous prenez un v\u00e9hicule privatif l\u2019ap\u00e9ritif n\u2019est pas inclus. Il faudra compter 15 euros suppl\u00e9mentaires par personne en suppl\u00e9ment pour cet ap\u00e9ritif dinatoire.  Au programme pour la journ\u00e9e VIP : Une exp\u00e9rience totalement privatis\u00e9e : votre groupe est seul avec notre guide, pour d\u00e9couvrir l\u2019arri\u00e8re-pays comme personne. Gr\u00e2ce au 4x4, vous empruntez des pistes confidentielles et des routes peu connues, bien loin des sentiers classiques, pour acc\u00e9der aux panoramas et secrets les mieux gard\u00e9s du Pays Basque. Au d\u00e9part de la c\u00f4te, vous traversez les villages embl\u00e9matiques (Arcangues, Saint-P\u00e9e-sur-Nivelle, Espelette, Itxassou, Ainhoa, Sare...)\u00a0avec possibilit\u00e9 de poursuivre jusqu\u2019en Espagne selon vos envies. ***D\u00e9jeuner non-compris : Le d\u00e9jeuner se fera en fonction de vos envies : pique-nique en pleine nature, \"venta\" traditionnelle, restaurant gastronomique... tout est possible.   Exp\u00e9rience \u00e0 bord : Pour les r\u00e9servations de 2 personnes : Vous partagerez l\u2019aventure \u00e0 bord de nos v\u00e9hicules avec nos accompagnateurs. Bien entendu, votre petit groupe restera ensemble, pour profiter pleinement de l\u2019exp\u00e9rience dans une ambiance conviviale et chaleureuse. Pour les r\u00e9servations de 4\/5 personnes : Vous profiterez d\u2019un v\u00e9hicule privatis\u00e9 rien que pour vous ! Le groupe vivra l\u2019exp\u00e9rience en toute intimit\u00e9, guid\u00e9 par l\u2019un de nos instructeurs certifi\u00e9s (qui sera dans un autre v\u00e9hicule devant vous)  Niveau : Aucun niveau particulier n\u2019est requis. Nos guides, formateurs dipl\u00f4m\u00e9s, sont l\u00e0 pour vous accompagner \u00e0 chaque instant : vous guider, vous conseiller et vous rassurer si n\u00e9cessaire. Vous n\u2019avez qu\u2019\u00e0 vous laisser porter par l\u2019exp\u00e9rience. Seul un permis en cours de validit\u00e9 est demand\u00e9.  Dates :\u00a0 Plusieurs dates sont propos\u00e9es pour 2026 du mois d'avril au mois de novembre. Le choix se fait sur ces dates. L\u2019exp\u00e9rience VIP est programm\u00e9e selon vos pr\u00e9f\u00e9rences : vous choisissez la date, nous nous occupons du reste. Vous aurez l'embarras du choix pour choisir le cr\u00e9neau qui vous convient.","og_url":"https:\/\/www.pays-basque-experience.com\/es\/producto-2\/bon-cadeau-decouverte\/","og_site_name":"Pays Basque Experience","article_modified_time":"2026-06-14T17:39:35+00:00","og_image":[{"width":787,"height":525,"url":"https:\/\/www.pays-basque-experience.com\/wp-content\/uploads\/2021\/11\/Coucher-soleil-groupe.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.pays-basque-experience.com\/produit\/bon-cadeau-decouverte\/","url":"https:\/\/www.pays-basque-experience.com\/produit\/bon-cadeau-decouverte\/","name":"Bon Cadeau D\u00e9couverte en 4x4 - Pays Basque Experience","isPartOf":{"@id":"https:\/\/www.pays-basque-experience.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.pays-basque-experience.com\/produit\/bon-cadeau-decouverte\/#primaryimage"},"image":{"@id":"https:\/\/www.pays-basque-experience.com\/produit\/bon-cadeau-decouverte\/#primaryimage"},"thumbnailUrl":"https:\/\/www.pays-basque-experience.com\/wp-content\/uploads\/2021\/11\/Coucher-soleil-groupe.jpg","datePublished":"2021-11-30T13:42:07+00:00","dateModified":"2026-06-14T17:39:35+00:00","breadcrumb":{"@id":"https:\/\/www.pays-basque-experience.com\/produit\/bon-cadeau-decouverte\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.pays-basque-experience.com\/produit\/bon-cadeau-decouverte\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.pays-basque-experience.com\/produit\/bon-cadeau-decouverte\/#primaryimage","url":"https:\/\/www.pays-basque-experience.com\/wp-content\/uploads\/2021\/11\/Coucher-soleil-groupe.jpg","contentUrl":"https:\/\/www.pays-basque-experience.com\/wp-content\/uploads\/2021\/11\/Coucher-soleil-groupe.jpg","width":787,"height":525},{"@type":"BreadcrumbList","@id":"https:\/\/www.pays-basque-experience.com\/produit\/bon-cadeau-decouverte\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.pays-basque-experience.com\/"},{"@type":"ListItem","position":2,"name":"Boutique","item":"https:\/\/www.pays-basque-experience.com\/boutique\/"},{"@type":"ListItem","position":3,"name":"Bon Cadeau D\u00e9couverte en 4&#215;4"}]},{"@type":"WebSite","@id":"https:\/\/www.pays-basque-experience.com\/#website","url":"https:\/\/www.pays-basque-experience.com\/","name":"Pays Basque Experience","description":"Aventures au Pays Basque - Rando 4x4 pays basque.","publisher":{"@id":"https:\/\/www.pays-basque-experience.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pays-basque-experience.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.pays-basque-experience.com\/#organization","name":"Pays Basque Experience","url":"https:\/\/www.pays-basque-experience.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.pays-basque-experience.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.pays-basque-experience.com\/wp-content\/uploads\/2021\/12\/cropped-logo-21A1.png","contentUrl":"https:\/\/www.pays-basque-experience.com\/wp-content\/uploads\/2021\/12\/cropped-logo-21A1.png","width":300,"height":300,"caption":"Pays Basque Experience"},"image":{"@id":"https:\/\/www.pays-basque-experience.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.pays-basque-experience.com\/es\/wp-json\/wp\/v2\/product\/668","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pays-basque-experience.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.pays-basque-experience.com\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.pays-basque-experience.com\/es\/wp-json\/wp\/v2\/media\/6459"}],"wp:attachment":[{"href":"https:\/\/www.pays-basque-experience.com\/es\/wp-json\/wp\/v2\/media?parent=668"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.pays-basque-experience.com\/es\/wp-json\/wp\/v2\/product_brand?post=668"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.pays-basque-experience.com\/es\/wp-json\/wp\/v2\/product_cat?post=668"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.pays-basque-experience.com\/es\/wp-json\/wp\/v2\/product_tag?post=668"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}